{"id":262,"date":"2023-03-11T22:00:00","date_gmt":"2023-03-11T21:00:00","guid":{"rendered":"https:\/\/vivalainfo.com\/kako-poiskati-parkiran-avto-s-pametnim-telefonom\/"},"modified":"2023-03-11T22:00:00","modified_gmt":"2023-03-11T21:00:00","slug":"kako-poiskati-parkiran-avto-s-pametnim-telefonom","status":"publish","type":"post","link":"https:\/\/viva.racunalniske-novice.com\/fr\/comment-trouver-une-voiture-garee-avec-un-smartphone\/","title":{"rendered":"Comment retrouver une voiture gar\u00e9e avec un smartphone ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u00c0 certains endroits, les places de stationnement sont signal\u00e9es par des chiffres et des lettres sp\u00e9ciaux pour une orientation plus facile, mais si nous sommes press\u00e9s, nous pouvons manquer ces panneaux ou m\u00eame ne pas les remarquer. Il y a eu aussi quelques cas surprenants o\u00f9 des connaissances ou des enregistrements en ligne nous ont avertis que se garer \u00e0 Ljubljana n&#039;est pas vraiment facile, surtout pour ceux qui ne visitent pas fr\u00e9quemment la capitale. Les parkings publics et organis\u00e9s sont souvent pleins ou trop chers, de sorte que les conducteurs irr\u00e9guliers empruntent les rues secondaires, qui peuvent \u00eatre plus difficiles \u00e0 trouver quelques heures plus tard et dans l&#039;obscurit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ne vous inqui\u00e9tez pas, pour chaque probl\u00e8me, il existe des applications qui nous facilitent la vie. Dans ce cas, les c\u00e9l\u00e8bres Google Maps et Apple Maps peuvent \u00eatre nos sauveurs, mais il existe \u00e9galement de nombreuses applications tierces qui abordent le m\u00eame probl\u00e8me sous un angle diff\u00e9rent. Voyons le moyen le plus simple de trouver une voiture gar\u00e9e avec un smartphone.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/03\/Screenshot_2023-03-01-11-44-24-904_com.google.android.apps_.maps_-461x1024.jpg\" alt=\"\" data-id=\"2237014\" data-full-url=\"\/wp-content\/uploads\/2023\/03\/Screenshot_2023-03-01-11-44-24-904_com.google.android.apps_.maps_-scaled.jpg\" data-link=\"\/?attachment_id=2237014\" class=\"wp-image-2237014\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/03\/Screenshot_2023-03-01-11-45-04-138_com.google.android.apps_.maps_-461x1024.jpg\" alt=\"\" data-id=\"2237016\" data-full-url=\"\/wp-content\/uploads\/2023\/03\/Screenshot_2023-03-01-11-45-04-138_com.google.android.apps_.maps_-scaled.jpg\" data-link=\"\/?attachment_id=2237016\" class=\"wp-image-2237016\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Google Maps<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Google Maps est une application fantastique que nous utilisons le plus souvent pour nous orienter dans de nouveaux endroits. Oh, le plus <a href=\"https:\/\/viva.racunalniske-novice.com\/fr\/astuces-google-maps-que-vous-devriez-commencer-a-utiliser\/\">astuces cach\u00e9es Google Lo<\/a><a href=\"https:\/\/viva.racunalniske-novice.com\/fr\/astuces-google-maps-que-vous-devriez-commencer-a-utiliser\/\" target=\"_blank\" rel=\"noreferrer noopener\">k<\/a><a href=\"https:\/\/viva.racunalniske-novice.com\/fr\/astuces-google-maps-que-vous-devriez-commencer-a-utiliser\/\">applications d&#039;ation<\/a> nous avons d\u00e9j\u00e0 \u00e9crit, \u00e9galement sur les applications alternatives, si par hasard nous ne sommes pas satisfaits de la solution de Google. Cependant, \u00e0 cette \u00e9poque, nous n&#039;avions pas mentionn\u00e9 la fonction qui m\u00e9morise l&#039;emplacement de la voiture gar\u00e9e. L&#039;astuce fonctionne pour les utilisateurs d&#039;Android et d&#039;iOS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comment \u00e7a fonctionne? Tout d\u2019abord, trouvez une place de parking vide, ouvrez Google Maps sur votre t\u00e9l\u00e9phone et cliquez sur l\u2019\u00e9pingle bleue (ou le cercle en bas \u00e0 droite) qui localisera votre position actuelle (vous devez avoir activ\u00e9 la localisation). Ensuite vous cliquez sur l&#039;endroit o\u00f9 vous vous trouvez (cercle bleu sur la carte). Une barre d&#039;outils appara\u00eetra dans laquelle vous pourrez s\u00e9lectionner la fonction Enregistrer le stationnement. Vous remarquerez alors une \u00e9pingle rouge sur la Carte qui indique une place de stationnement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les utilisateurs d&#039;Android peuvent saisir un peu plus d&#039;informations, comme le nombre d&#039;heures que vous avez pay\u00e9es pour une place de stationnement et d&#039;autres notes suppl\u00e9mentaires, comme les plaques d&#039;immatriculation des voitures \u00e0 proximit\u00e9, si vous \u00eates parano\u00efaque \u00e0 l&#039;id\u00e9e que quelqu&#039;un gratte votre voiture. Bien entendu, ce n\u2019est pas une solution 100 % fiable. Vous pouvez \u00e9galement partager l&#039;emplacement de la voiture gar\u00e9e avec d&#039;autres personnes, par exemple avec un partenaire qui pourrait en avoir assez d&#039;explorer le centre commercial plus t\u00f4t.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu&#039;il est temps de retourner \u00e0 votre voiture gar\u00e9e, cliquez sur l&#039;emplacement marqu\u00e9 ou sur l&#039;\u00e9pingle sur la carte et s\u00e9lectionnez Itin\u00e9raire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cartes Apple<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de pouvoir utiliser Apple Maps pour trouver une voiture gar\u00e9e, vous devez d&#039;abord modifier certains param\u00e8tres. Sur votre iPhone, acc\u00e9dez \u00e0 Param\u00e8tres &gt; Confidentialit\u00e9 et s\u00e9curit\u00e9 &gt; Services de localisation et assurez-vous que les services de localisation sont activ\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Faites d\u00e9filer vers le bas de l\u2019\u00e9cran Services de localisation, s\u00e9lectionnez Services syst\u00e8me, puis appuyez sur Emplacements importants. Le syst\u00e8me peut vous demander de saisir un mot de passe, Touch ID ou Face ID. Ensuite, activez le commutateur \u00e0 c\u00f4t\u00e9 de la fonction Points d\u2019int\u00e9r\u00eat. Acc\u00e9dez ensuite \u00e0 Param\u00e8tres &gt; Cartes et activez la fonction Afficher l&#039;emplacement de stationnement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez d\u00e9sormais suivre l&#039;emplacement de votre voiture lorsqu&#039;elle est gar\u00e9e. Votre iPhone le fera automatiquement si vous le connectez via Bluetooth ou CarPlay. Lorsque vous vous d\u00e9connectez de la voiture, votre t\u00e9l\u00e9phone devrait afficher une notification indiquant que l&#039;application Apple Maps a marqu\u00e9 l&#039;emplacement de la voiture gar\u00e9e. Si la notification n&#039;appara\u00eet pas, vous n&#039;utilisez pas CarPlay ou votre t\u00e9l\u00e9phone n&#039;est pas connect\u00e9 \u00e0 la voiture via Bluetooth. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce cas, vous pouvez localiser la place de parking manuellement. Ouvrez Apple Maps et recherchez une \u00e9pingle bleue pour un v\u00e9hicule gar\u00e9 sur la carte, puis appuyez dessus. Si vous ne le voyez pas, tapez \u00ab voiture gar\u00e9e \u00bb dans le champ de recherche et l&#039;emplacement de la voiture devrait appara\u00eetre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Appuyez sur le bouton Modifier l&#039;emplacement pour voir une photo des environs de votre voiture. Vous pouvez \u00e9galement cr\u00e9er une note avec plus de d\u00e9tails et appuyer sur le bouton Ajouter une photo pour prendre une photo de votre voiture et de votre emplacement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous avez besoin de trouver votre voiture, ouvrez Apple Maps et appuyez sur l&#039;\u00e9pingle du v\u00e9hicule gar\u00e9. S\u00e9lectionnez Itin\u00e9raire, puis appuyez sur Aller pour suivre les indications \u00e0 pied jusqu&#039;\u00e0 votre voiture gar\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija-576x1024.webp\" alt=\"comment trouver une voiture gar\u00e9e 1\" data-id=\"2237008\" data-full-url=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija.webp\" data-link=\"\/?attachment_id=2237008\" class=\"wp-image-2237008\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija1-576x1024.webp\" alt=\"comment trouver une voiture gar\u00e9e\" data-id=\"2237006\" data-full-url=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija1.webp\" data-link=\"\/?attachment_id=2237006\" class=\"wp-image-2237006\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Applications tierces<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Parking<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">C&#039;est le roi autoproclam\u00e9 des applications de stationnement <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=il.talent.parking\" target=\"_blank\" rel=\"noreferrer noopener\">Parking<\/a>. L&#039;application marque automatiquement l&#039;endroit o\u00f9 vous avez gar\u00e9 votre voiture. Comment? Dans l&#039;application, vous devez d&#039;abord activer le marquage automatique d&#039;une voiture gar\u00e9e dans les param\u00e8tres. Lorsque l&#039;application d\u00e9tecte que votre t\u00e9l\u00e9phone a perdu la connexion Bluetooth avec la voiture, elle marquera cet endroit comme place de stationnement. ParKing ne fonctionne pas en arri\u00e8re-plan, vous n&#039;avez donc pas \u00e0 craindre qu&#039;il consomme trop de batterie de votre t\u00e9l\u00e9phone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il enregistre \u00e9galement toutes les places de stationnement pr\u00e9c\u00e9demment marqu\u00e9es (marqu\u00e9es manuellement ou automatiquement). Vous pouvez modifier, supprimer ou ajouter des notes \u00e0 chaque balise. Lorsqu&#039;aucun signal GPS n&#039;est disponible, vous pouvez ajouter une photo de l&#039;espace de stationnement et toutes les autres instructions n\u00e9cessaires pour trouver la voiture de mani\u00e8re fiable.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija2-485x1024.webp\" alt=\"comment trouver une voiture gar\u00e9e 3\" data-id=\"2237004\" data-full-url=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija2.webp\" data-link=\"\/?attachment_id=2237004\" class=\"wp-image-2237004\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija3-485x1024.webp\" alt=\"comment trouver une voiture gar\u00e9e 2\" data-id=\"2237002\" data-full-url=\"\/wp-content\/uploads\/2023\/03\/parking-aplikacija3.webp\" data-link=\"\/?attachment_id=2237002\" class=\"wp-image-2237002\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trouver ma voiture, localisateur de voiture gar\u00e9e...<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=pl.hostuptime.carlocator\" target=\"_blank\" rel=\"noreferrer noopener\">Localisateur de voiture gar\u00e9e<\/a> et <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.discipleskies.aaafindmycar\" target=\"_blank\" rel=\"noreferrer noopener\">Trouver ma voiture<\/a> sont des applications basiques et surtout tr\u00e8s simples \u00e0 utiliser. Marquez l&#039;emplacement de la place de stationnement et, lorsqu&#039;il est temps de revenir, suivez la boussole sur la carte. Dans l&#039;application Find my Car, vous pouvez \u00e9galement ajouter des coordonn\u00e9es et une photo de la voiture gar\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trouvez votre voiture avec AR<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/03\/waze-576x1024.webp\" alt=\"\" class=\"wp-image-2237010\" width=\"210\" height=\"374\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Le processus est similaire aux demandes pr\u00e9c\u00e9dentes. Pour revenir, vous pouvez utiliser la technologie de r\u00e9alit\u00e9 augment\u00e9e (AR), qui transforme la carte normale en <a href=\"https:\/\/apps.apple.com\/us\/app\/find-your-car-with-ar-augmented-car-finder\/id370836023\" target=\"_blank\" rel=\"noreferrer noopener\">Carte AR<\/a> avec les environs r\u00e9els affich\u00e9s, ce qui signifie qu&#039;il vous sera plus facile de naviguer autour des b\u00e2timents voisins pendant votre recherche.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Waze<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.waze&amp;hl=sl&amp;gl=US\" target=\"_blank\" rel=\"noreferrer noopener\">Waze <\/a>est une alternative populaire \u00e0 l&#039;application Google Maps qui offre \u00e9galement la fonction de sauvegarde automatique d&#039;une place de parking. La condition est que vous ayez pr\u00e9alablement utilis\u00e9 l&#039;application pour naviguer vers votre destination finale. Lorsque vous fermez l&#039;application, elle marquera automatiquement l&#039;emplacement de la voiture sur la carte. Suivez ensuite simplement les indications pour regagner votre voiture.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Samsung Bixby, Samsung SmartThings, Apple AirTags...<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Assistant num\u00e9rique Bixby <a href=\"https:\/\/viva.racunalniske-novice.com\/fr\/test-samsung-galaxy-s23-ultra-super-telephone\/\" target=\"_blank\" rel=\"noreferrer noopener\">Utilisateurs Samsung<\/a> lui permet de m\u00e9moriser automatiquement l&#039;emplacement de la voiture gar\u00e9e pour eux. Vous devez d&#039;abord activer la fonctionnalit\u00e9 dans les param\u00e8tres Bixby.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Samsung dispose d&#039;une fonctionnalit\u00e9 SmartThings pratique qui vous permet de vous connecter \u00e0 des appareils Bluetooth externes tels que <a href=\"https:\/\/amzn.to\/3y0akOX\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9tiquette intelligente Samsung<\/a> (40 \u20ac pour deux balises). Laissez le localisateur dans la voiture, par exemple dans un tiroir ou un accoudoir. D\u00e9crochez votre t\u00e9l\u00e9phone, connectez-vous \u00e0 un dispositif de suivi \u00e0 l&#039;aide de SmartThings et trouvez votre voiture. C\u2019est \u00e9galement une excellente solution pr\u00e9ventive en cas de vol de voiture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#039;alternative d&#039;Apple est les localisateurs <a href=\"https:\/\/www.bigbang.si\/apple-airtag-1-pack-pametni-sledilnik-izdelek-152013\/?utm_source=ceneje&amp;utm_medium=products&amp;utm_campaign=ceneje_products&amp;utm_content=pp_p_2\" target=\"_blank\" rel=\"noreferrer noopener\">AirTags<\/a>, qui fonctionnent de mani\u00e8re tr\u00e8s similaire (36 \u20ac pour 1 traceur). Ils sont \u00e9galement pratiques pour localiser d&#039;autres objets, par exemple des bagages en cas de perte dans les a\u00e9roports, etc.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dans certains endroits, les places de stationnement sont signal\u00e9es par des num\u00e9ros et des lettres sp\u00e9ciaux pour faciliter l&#039;orientation, mais si nous sommes press\u00e9s, nous pouvons ignorer ces marquages ou m\u00eame ne pas les remarquer. Il y a \u00e9galement eu quelques cas surprenants o\u00f9 des connaissances ou des publications en ligne nous ont avertis que se garer \u00e0 Ljubljana n\u2019est pas vraiment facile, surtout pour [\u2026]<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[74,4,52,50,12],"tags":[],"class_list":["post-262","post","type-post","status-publish","format-standard","hentry","category-aplikacije","category-racunalnistvo-telefonija","category-telefoni","category-telefonija","category-triki-nasveti"],"acf":{"subtitle":"V mestih, ki nam niso znana, in v ogromnih parkirnih hi\u0161ah se lahko hitro zgodi, da pozabimo, kje smo parkirali svojega jeklenega konji\u010dka, na katerega ra\u010dunamo, da nas bo varno pripeljal domov. ","heading":"","summary":"V mestih, ki nam niso znana, in v ogromnih parkirnih hi\u0161ah se lahko hitro zgodi, da pozabimo, kje smo parkirali svojega jeklenega konji\u010dka, na katerega ra\u010dunamo, da nas bo varno pripeljal domov. ","thumbnail_small":"https:\/\/racunalniske-novice.com\/wp-content\/uploads\/2023\/03\/mitchell-griest-eLC759ueVQw-unsplash-560x315.jpg","thumbnail_large":"https:\/\/racunalniske-novice.com\/wp-content\/uploads\/2023\/03\/mitchell-griest-eLC759ueVQw-unsplash-1024x684.jpg","thumbnail_caption":"Foto: Unsplash","gallery":"","video_gallery":null,"author":"","links":null,"sources":null,"skip_language":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kako poiskati parkiran avto s pametnim telefonom? - Ra\u010dunalni\u0161ke novice<\/title>\n<meta name=\"description\" content=\"V mestih, ki nam niso znana, in v ogromnih parkirnih hi\u0161ah se lahko hitro zgodi, da pozabimo, kje smo parkirali svojega jeklenega konji\u010dka, na katerega ra\u010dunamo, da nas bo varno pripeljal domov.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/posts\/262\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kako poiskati parkiran avto s pametnim telefonom? - Ra\u010dunalni\u0161ke novice\" \/>\n<meta property=\"og:description\" content=\"Ponekod so parkirna mesta ozna\u010dena s posebnimi \u0161tevilkami in \u010drkami za la\u017ejo orientacijo, a \u010de se nam mudi, lahko spregledamo te oznake ali pa jih niti ne opazimo. Bilo je tudi kar nekaj presenetljivih primerov, ko so nas znanci ali pa zapisi na spletu opozorili, da parkiranje v Ljubljani ni ravno enostavno, \u0161e posebej za [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viva.racunalniske-novice.com\/fr\/how-to-find-a-parked-car-with-a-smartphone\/\" \/>\n<meta property=\"og:site_name\" content=\"Ra\u010dunalni\u0161ke novice\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-11T21:00:00+00:00\" \/>\n<meta name=\"author\" content=\"sinusiks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sinusiks\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/\",\"url\":\"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/\",\"name\":\"Kako poiskati parkiran avto s pametnim telefonom? - Ra\u010dunalni\u0161ke novice\",\"isPartOf\":{\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#website\"},\"datePublished\":\"2023-03-11T21:00:00+00:00\",\"dateModified\":\"2023-03-11T21:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4\"},\"breadcrumb\":{\"@id\":\"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/viva.racunalniske-novice.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kako poiskati parkiran avto s pametnim telefonom?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#website\",\"url\":\"https:\/\/viva.racunalniske-novice.com\/en\/\",\"name\":\"Ra\u010dunalni\u0161ke novice\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/viva.racunalniske-novice.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4\",\"name\":\"sinusiks\",\"sameAs\":[\"https:\/\/ml.racunalniske-novice.com\"],\"url\":\"https:\/\/viva.racunalniske-novice.com\/fr\/author\/sinusiks\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kako poiskati parkiran avto s pametnim telefonom? - Ra\u010dunalni\u0161ke novice","description":"V mestih, ki nam niso znana, in v ogromnih parkirnih hi\u0161ah se lahko hitro zgodi, da pozabimo, kje smo parkirali svojega jeklenega konji\u010dka, na katerega ra\u010dunamo, da nas bo varno pripeljal domov.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/posts\/262","og_locale":"fr_FR","og_type":"article","og_title":"Kako poiskati parkiran avto s pametnim telefonom? - Ra\u010dunalni\u0161ke novice","og_description":"Ponekod so parkirna mesta ozna\u010dena s posebnimi \u0161tevilkami in \u010drkami za la\u017ejo orientacijo, a \u010de se nam mudi, lahko spregledamo te oznake ali pa jih niti ne opazimo. Bilo je tudi kar nekaj presenetljivih primerov, ko so nas znanci ali pa zapisi na spletu opozorili, da parkiranje v Ljubljani ni ravno enostavno, \u0161e posebej za [&hellip;]","og_url":"https:\/\/viva.racunalniske-novice.com\/fr\/how-to-find-a-parked-car-with-a-smartphone\/","og_site_name":"Ra\u010dunalni\u0161ke novice","article_published_time":"2023-03-11T21:00:00+00:00","author":"sinusiks","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"sinusiks","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/","url":"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/","name":"Kako poiskati parkiran avto s pametnim telefonom? - Ra\u010dunalni\u0161ke novice","isPartOf":{"@id":"https:\/\/viva.racunalniske-novice.com\/en\/#website"},"datePublished":"2023-03-11T21:00:00+00:00","dateModified":"2023-03-11T21:00:00+00:00","author":{"@id":"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4"},"breadcrumb":{"@id":"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/viva.racunalniske-novice.com\/how-to-find-a-parked-car-with-a-smartphone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/viva.racunalniske-novice.com\/en\/"},{"@type":"ListItem","position":2,"name":"Kako poiskati parkiran avto s pametnim telefonom?"}]},{"@type":"WebSite","@id":"https:\/\/viva.racunalniske-novice.com\/en\/#website","url":"https:\/\/viva.racunalniske-novice.com\/en\/","name":"Ra\u010dunalni\u0161ke novice","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viva.racunalniske-novice.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4","name":"sinusiks","sameAs":["https:\/\/ml.racunalniske-novice.com"],"url":"https:\/\/viva.racunalniske-novice.com\/fr\/author\/sinusiks\/"}]}},"_links":{"self":[{"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/posts\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/comments?post=262"}],"version-history":[{"count":0,"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/posts\/262\/revisions"}],"wp:attachment":[{"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/categories?post=262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/fr\/wp-json\/wp\/v2\/tags?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}