{"id":7819,"date":"2026-07-14T13:45:00","date_gmt":"2026-07-14T11:45:00","guid":{"rendered":"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/"},"modified":"2026-07-14T13:45:00","modified_gmt":"2026-07-14T11:45:00","slug":"iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov","status":"publish","type":"post","link":"https:\/\/viva.racunalniske-novice.com\/it\/la-ricerca-di-windows-ora-e-piu-veloce-e-priva-di-fastidiose-pubblicita\/","title":{"rendered":"La ricerca di Windows ora \u00e8 pi\u00f9 veloce e priva di fastidiose pubblicit\u00e0."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Gli utenti di Windows 11 si lamentavano da tempo del fatto che il motore di ricerca di sistema spesso restituisse risultati online e annunci pubblicitari anzich\u00e9 file locali. Microsoft ha finalmente affrontato queste critiche, rinnovando questa popolare funzionalit\u00e0 della barra delle applicazioni nell&#039;ultimo aggiornamento di Windows Insider.<br><br>La principale novit\u00e0 che gli utenti noteranno cliccando sulla barra di ricerca \u00e8 la completa rimozione degli annunci pubblicitari. Nell&#039;attuale versione stabile, all&#039;apertura del motore di ricerca vengono visualizzate due colonne: una con la cronologia delle ricerche precedenti e la seconda, molto pi\u00f9 ampia, dedicata alla promozione di servizi e applicazioni Microsoft. Nella versione aggiornata, questi annunci sono stati completamente eliminati. Il sistema utilizzer\u00e0 lo spazio liberato per visualizzare informazioni pi\u00f9 dettagliate sulle ricerche effettuate in precedenza.<br><br>I risultati della ricerca sono ora molto pi\u00f9 chiaramente separati ed evidenziati graficamente, consentendo all&#039;utente di riconoscere immediatamente se si tratta dell&#039;avvio di un&#039;applicazione, dell&#039;apertura delle impostazioni di sistema, di un file locale o di un sito Web esterno. Inoltre, Microsoft sta introducendo anteprime pi\u00f9 grandi per i tipi di file supportati e la possibilit\u00e0 di selezionare rapidamente l&#039;opzione &quot;Apri con&quot; direttamente nella finestra di ricerca.<br><br>La ricerca di sistema ora dar\u00e0 priorit\u00e0 ai risultati locali. Ad esempio, se si cerca un&#039;impostazione di sistema specifica o si digita il nome di un programma in modo errato, il motore di ricerca non reindirizzer\u00e0 pi\u00f9 automaticamente l&#039;utente a una ricerca sul web, ma tenter\u00e0 invece di trovare un risultato corrispondente sul disco. Anche se una ricerca sul web \u00e8 inevitabile, non verranno pi\u00f9 visualizzati annunci pubblicitari nella parte superiore della pagina, ma i risultati web effettivi appariranno direttamente in cima all&#039;elenco, senza bisogno di scorrere verso il basso.<br><br>Trattandosi di un aggiornamento sperimentale, la funzionalit\u00e0 viene implementata gradualmente, il che significa che potrebbe non essere ancora disponibile per tutti i tester. Microsoft non ha ancora stabilito una data ufficiale per l&#039;inclusione di questo miglioramento nella versione stabile del sistema, destinata a tutti gli utenti finali. Essendo in fase di test, alcuni dettagli potrebbero subire modifiche prima del rilascio definitivo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Uporabniki operacijskega sistema Windows 11 so \u017ee dlje \u010dasa izra\u017eali nezadovoljstvo nad delovanjem sistemskega iskalnika, ki je pogosto namesto lokalnih datotek ponujal spletne rezultate in oglase. Microsoft se je na te kritike kon\u010dno odzval ter v najnovej\u0161i posodobitvi za razvijalce oziroma preizku\u0161evalce (Windows Insider) temeljito preuredil to priljubljeno funkcijo v opravilni vrstici. Glavna sprememba, ki [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[68],"tags":[220],"class_list":["post-7819","post","type-post","status-publish","format-standard","hentry","category-operacijski-sistemi","tag-windows-11"],"acf":{"subtitle":"","heading":"","summary":"Microsoft v Windows 11 uvaja prenovljen iskalnik, ki izlo\u010da oglase in daje prednost lokalnim datotekam pred spletom. Posodobitev je trenutno na voljo preizku\u0161evalcem v testnem kanalu, datum uradnega izida za vse uporabnike pa \u0161e ni znan.","thumbnail_small":"https:\/\/racunalniske-novice.com\/wp-content\/uploads\/2025\/04\/Windows-1122-1024x576-1-560x315.jpg","thumbnail_large":"https:\/\/racunalniske-novice.com\/wp-content\/uploads\/2025\/04\/Windows-1122-1024x576-1.jpg","thumbnail_caption":"","gallery":"","video_gallery":null,"author":"","links":null,"sources":[{"title":"notebookcheck","url":"https:\/\/www.notebookcheck.net\/Windows-11-gets-completely-revamped-search-without-ads.1341907.0.html"}],"skip_language":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov - Ra\u010dunalni\u0161ke novice<\/title>\n<meta name=\"description\" content=\"Microsoft v Windows 11 uvaja prenovljen iskalnik, ki izlo\u010da oglase in daje prednost lokalnim datotekam pred spletom. Posodobitev je trenutno na voljo preizku\u0161evalcem v testnem kanalu, datum uradnega i\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/posts\/7819\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov - Ra\u010dunalni\u0161ke novice\" \/>\n<meta property=\"og:description\" content=\"Uporabniki operacijskega sistema Windows 11 so \u017ee dlje \u010dasa izra\u017eali nezadovoljstvo nad delovanjem sistemskega iskalnika, ki je pogosto namesto lokalnih datotek ponujal spletne rezultate in oglase. Microsoft se je na te kritike kon\u010dno odzval ter v najnovej\u0161i posodobitvi za razvijalce oziroma preizku\u0161evalce (Windows Insider) temeljito preuredil to priljubljeno funkcijo v opravilni vrstici. Glavna sprememba, ki [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viva.racunalniske-novice.com\/it\/la-ricerca-di-windows-ora-e-piu-veloce-e-priva-di-fastidiose-pubblicita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ra\u010dunalni\u0161ke novice\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T11:45:00+00:00\" \/>\n<meta name=\"author\" content=\"sinusiks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sinusiks\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/\",\"url\":\"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/\",\"name\":\"Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov - Ra\u010dunalni\u0161ke novice\",\"isPartOf\":{\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#website\"},\"datePublished\":\"2026-07-14T11:45:00+00:00\",\"dateModified\":\"2026-07-14T11:45:00+00:00\",\"author\":{\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4\"},\"breadcrumb\":{\"@id\":\"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/viva.racunalniske-novice.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#website\",\"url\":\"https:\/\/viva.racunalniske-novice.com\/en\/\",\"name\":\"Ra\u010dunalni\u0161ke novice\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/viva.racunalniske-novice.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4\",\"name\":\"sinusiks\",\"sameAs\":[\"https:\/\/ml.racunalniske-novice.com\"],\"url\":\"https:\/\/viva.racunalniske-novice.com\/it\/author\/sinusiks\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov - Ra\u010dunalni\u0161ke novice","description":"Microsoft v Windows 11 uvaja prenovljen iskalnik, ki izlo\u010da oglase in daje prednost lokalnim datotekam pred spletom. Posodobitev je trenutno na voljo preizku\u0161evalcem v testnem kanalu, datum uradnega i","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/posts\/7819","og_locale":"it_IT","og_type":"article","og_title":"Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov - Ra\u010dunalni\u0161ke novice","og_description":"Uporabniki operacijskega sistema Windows 11 so \u017ee dlje \u010dasa izra\u017eali nezadovoljstvo nad delovanjem sistemskega iskalnika, ki je pogosto namesto lokalnih datotek ponujal spletne rezultate in oglase. Microsoft se je na te kritike kon\u010dno odzval ter v najnovej\u0161i posodobitvi za razvijalce oziroma preizku\u0161evalce (Windows Insider) temeljito preuredil to priljubljeno funkcijo v opravilni vrstici. Glavna sprememba, ki [&hellip;]","og_url":"https:\/\/viva.racunalniske-novice.com\/it\/la-ricerca-di-windows-ora-e-piu-veloce-e-priva-di-fastidiose-pubblicita\/","og_site_name":"Ra\u010dunalni\u0161ke novice","article_published_time":"2026-07-14T11:45:00+00:00","author":"sinusiks","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"sinusiks","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/","url":"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/","name":"Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov - Ra\u010dunalni\u0161ke novice","isPartOf":{"@id":"https:\/\/viva.racunalniske-novice.com\/en\/#website"},"datePublished":"2026-07-14T11:45:00+00:00","dateModified":"2026-07-14T11:45:00+00:00","author":{"@id":"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4"},"breadcrumb":{"@id":"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/viva.racunalniske-novice.com\/iskanje-na-windowsu-bo-odslej-hitrejse-in-brez-nadleznih-oglasov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/viva.racunalniske-novice.com\/en\/"},{"@type":"ListItem","position":2,"name":"Iskanje na Windowsu bo odslej hitrej\u0161e in brez nadle\u017enih oglasov"}]},{"@type":"WebSite","@id":"https:\/\/viva.racunalniske-novice.com\/en\/#website","url":"https:\/\/viva.racunalniske-novice.com\/en\/","name":"Ra\u010dunalni\u0161ke novice","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viva.racunalniske-novice.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/viva.racunalniske-novice.com\/en\/#\/schema\/person\/afb62e36efa34516d50249517e4cdbb4","name":"sinusiks","sameAs":["https:\/\/ml.racunalniske-novice.com"],"url":"https:\/\/viva.racunalniske-novice.com\/it\/author\/sinusiks\/"}]}},"_links":{"self":[{"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/posts\/7819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/comments?post=7819"}],"version-history":[{"count":0,"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/posts\/7819\/revisions"}],"wp:attachment":[{"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/media?parent=7819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/categories?post=7819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viva.racunalniske-novice.com\/it\/wp-json\/wp\/v2\/tags?post=7819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}